{"id":617,"date":"2026-07-20T19:06:17","date_gmt":"2026-07-20T19:06:17","guid":{"rendered":"https:\/\/qat-1.multilingualpress.syde.wpinfra.cloud\/?p=617"},"modified":"2026-08-28T21:22:45","modified_gmt":"2026-08-28T21:22:45","slug":"post-di-prova-sulle-formalita","status":"publish","type":"post","link":"https:\/\/qat-1.multilingualpress.syde.wpinfra.cloud\/site-5\/blog\/2026\/07\/20\/post-di-prova-sulle-formalita\/","title":{"rendered":"Post di prova sulle formalit\u00e0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Grazie per il tuo recente acquisto. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ti informiamo che il tuo ordine \u00e8 stato confermato e che al momento \u00e8 in fase di preparazione per la spedizione. Il tuo pacco \u00e8 stato consegnato al nostro corriere e ti verr\u00e0 recapitato a breve. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puoi tracciare la spedizione in qualsiasi momento utilizzando il link di tracciamento fornito nell\u2019e-mail di conferma. Ti preghiamo di attendere fino a 48 ore prima che le informazioni di tracciamento siano disponibili. Se hai domande sul tuo ordine, il nostro team di assistenza clienti \u00e8 a tua disposizione dal luned\u00ec al venerd\u00ec, dalle 9:00 alle 18:00. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Saremo lieti di aiutarti per qualsiasi dubbio riguardante il tuo acquisto, la consegna o una richiesta di reso. Apprezziamo la tua fiducia e non vediamo l\u2019ora di servirti di nuovo in futuro. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Non esitare a contattarci se c\u2019\u00e8 qualcosa che possiamo fare per migliorare la tua esperienza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ti preghiamo di confermare l&#8217;ordine e di contattarci se hai domande.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"editor_notices":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-617","post","type-post","status-publish","format-standard","hentry","category-non-di-classe"],"acf":[],"_links":{"self":[{"href":"https:\/\/qat-1.multilingualpress.syde.wpinfra.cloud\/site-5\/wp-json\/wp\/v2\/posts\/617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qat-1.multilingualpress.syde.wpinfra.cloud\/site-5\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/qat-1.multilingualpress.syde.wpinfra.cloud\/site-5\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/qat-1.multilingualpress.syde.wpinfra.cloud\/site-5\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/qat-1.multilingualpress.syde.wpinfra.cloud\/site-5\/wp-json\/wp\/v2\/comments?post=617"}],"version-history":[{"count":70,"href":"https:\/\/qat-1.multilingualpress.syde.wpinfra.cloud\/site-5\/wp-json\/wp\/v2\/posts\/617\/revisions"}],"predecessor-version":[{"id":773,"href":"https:\/\/qat-1.multilingualpress.syde.wpinfra.cloud\/site-5\/wp-json\/wp\/v2\/posts\/617\/revisions\/773"}],"wp:attachment":[{"href":"https:\/\/qat-1.multilingualpress.syde.wpinfra.cloud\/site-5\/wp-json\/wp\/v2\/media?parent=617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/qat-1.multilingualpress.syde.wpinfra.cloud\/site-5\/wp-json\/wp\/v2\/categories?post=617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/qat-1.multilingualpress.syde.wpinfra.cloud\/site-5\/wp-json\/wp\/v2\/tags?post=617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}